{"id":47904,"date":"2026-05-12T17:53:32","date_gmt":"2026-05-12T17:53:32","guid":{"rendered":"https:\/\/chinesecousin.com\/index.php\/product\/nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89\/"},"modified":"2026-05-12T17:53:35","modified_gmt":"2026-05-12T17:53:35","slug":"nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89","status":"publish","type":"product","link":"https:\/\/chinesecousin.com\/index.php\/product\/nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89nm-blue-shoes-bag-set%ef%bc%88nm47%ef%bc%89\/","title":{"rendered":"NM-Blue Shoes &amp; Bag Set\uff08NM47\uff09NM-Blue Shoes &amp; Bag Set\uff08NM47\uff09"},"content":{"rendered":"<p>This color is best for summertime!<\/p>\n<p>Bag strap can be removable.<\/p>\n<p>Shoes women size from 6-12<\/p>\n<p>Bag Size:7.48*4.72*2.75inch<\/p>\n<\/p>\n<div><img decoding=\"async\" alt=\"\" data-mce-fragment=\"1\" data-mce-selected=\"1\" data-mce-src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0730\/1814\/7097\/files\/size_8a102f81-1399-4ab8-b7fc-7940468fc763_600x600.jpg?v=1702954299\" src=\"https:\/\/cdn.shopify.com\/s\/files\/1\/0730\/1814\/7097\/files\/size_8a102f81-1399-4ab8-b7fc-7940468fc763_600x600.jpg?v=1702954299\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>This color is best for summertime! Bag strap can be removable. Shoes women size from 6-12 Bag Size:7.48*4.72*2.75inch<\/p>\n","protected":false},"featured_media":47901,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[42],"product_tag":[],"class_list":{"0":"post-47904","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-shoes-nike","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-variable"},"_links":{"self":[{"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/product\/47904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/comments?post=47904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/media\/47901"}],"wp:attachment":[{"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/media?parent=47904"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=47904"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=47904"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/chinesecousin.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=47904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}